{"id":11775471,"date":"2025-11-01T08:49:00","date_gmt":"2025-11-01T12:49:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11775471"},"modified":"2025-11-01T08:39:42","modified_gmt":"2025-11-01T12:39:42","slug":"uems-recebe-ate-dia-6-de-novembro-inscricao-para-vestibular-2026","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/uems-recebe-ate-dia-6-de-novembro-inscricao-para-vestibular-2026\/","title":{"rendered":"UEMS recebe at\u00e9 dia 6 de novembro inscri\u00e7\u00e3o para Vestibular 2026"},"content":{"rendered":"<p style=\"font-weight: 400;\">O per\u00edodo de inscri\u00e7\u00f5es para o Vestibular 2026 da Universidade Estadual de Mato Grosso do Sul (UEMS) termina no pr\u00f3ximo dia 6 de novembro, pela p\u00e1gina da Funda\u00e7\u00e3o de Apoio \u00e0 Pesquisa, ao Ensino e \u00e0 Cultura \u2013 Fapec (<a href=\"https:\/\/concurso.fapec.org\/inscricoes-uems.php\">https:\/\/concurso.fapec.org\/inscricoes-uems.php<\/a>). A taxa de inscri\u00e7\u00e3o \u00e9 de R$ 100, com pagamento at\u00e9 7 de novembro.<\/p>\n<p style=\"font-weight: 400;\">As provas objetivas e de reda\u00e7\u00e3o ser\u00e3o realizadas no dia 23 de novembro, no per\u00edodo matutino, em 18 munic\u00edpios de Mato Grosso do Sul. O resultado final est\u00e1 previsto para 20 de janeiro de 2026.<\/p>\n<p style=\"font-weight: 400;\">O Vestibular UEMS 2026 oferece 871 vagas em cursos de gradua\u00e7\u00e3o presenciais, distribu\u00eddos por 14 unidades universit\u00e1rias. S\u00e3o diversos cursos, entre licenciaturas, bacharelados e tecnol\u00f3gicos, espalhados pelo Estado de Mato Grosso do Sul, refor\u00e7ando o papel da universidade na interioriza\u00e7\u00e3o do ensino p\u00fablico e gratuito e na forma\u00e7\u00e3o de profissionais que impulsionam o desenvolvimento regional.<\/p>\n<p style=\"font-weight: 400;\">&#8220;O UEMSVEST, Vestibular da Universidade Estadual de Mato Grosso do Sul (UEMS), \u00e9 uma oportunidade transformadora que pode moldar o futuro de nossos jovens.\u00a0Entrar na UEMS \u00e9 muito mais do que apenas conseguir um diploma. \u00c9 abrir portas para um mundo de possibilidades na vida profissional e pessoal desses nossos ingressantes&#8221;, diz o\u00a0Prof. Dr. La\u00e9rcio Alves de Carvalho.<\/p>\n<p style=\"font-weight: 400;\">Nesta edi\u00e7\u00e3o, o processo seletivo mant\u00e9m e amplia o compromisso com a inclus\u00e3o social e a valoriza\u00e7\u00e3o da diversidade. Al\u00e9m das cotas j\u00e1 existentes para negros(as), ind\u00edgenas e pessoas com defici\u00eancia, a UEMS reserva 10% das vagas para candidatos(as) que residem em Mato Grosso do Sul h\u00e1 mais de 10 anos. As vagas tamb\u00e9m contemplam o sistema de ampla concorr\u00eancia.<\/p>\n<p style=\"font-weight: 400;\">As provas ser\u00e3o aplicadas em fase \u00fanica, composta por Prova Objetiva, com 60 quest\u00f5es de m\u00faltipla escolha, e Prova de Reda\u00e7\u00e3o, ambas de car\u00e1ter classificat\u00f3rio. Os conte\u00fados abrangem as \u00e1reas de Linguagens, Matem\u00e1tica, Ci\u00eancias da Natureza e Ci\u00eancias Humanas, conforme o programa descrito no edital.<\/p>\n<p style=\"font-weight: 400;\"><b><strong>Servi\u00e7o \u2013 Vestibular UEMS 2026<\/strong><\/b><\/p>\n<p style=\"font-weight: 400;\">Per\u00edodo de inscri\u00e7\u00f5es: at\u00e9 6 de novembro de 2025<\/p>\n<p style=\"font-weight: 400;\">Taxa de inscri\u00e7\u00e3o: R$ 100,00 (pagamento at\u00e9 7 de novembro)<\/p>\n<p style=\"font-weight: 400;\">Data das provas: 23 de novembro de 2025<\/p>\n<p style=\"font-weight: 400;\">Inscri\u00e7\u00f5es e edital completo:\u00a0<a href=\"https:\/\/concurso.fapec.org\/inscricoes-uems.php\">https:\/\/concurso.fapec.org\/inscricoes-uems.php<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O per\u00edodo de inscri\u00e7\u00f5es para o Vestibular 2026 da Universidade Estadual de Mato Grosso do&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11773439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[194],"class_list":["post-11775471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-educacao"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11775471"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775471\/revisions"}],"predecessor-version":[{"id":11775472,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775471\/revisions\/11775472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11773439"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11775471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11775471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11775471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}