{"id":11775525,"date":"2025-11-04T09:29:32","date_gmt":"2025-11-04T13:29:32","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11775525"},"modified":"2025-11-04T09:37:05","modified_gmt":"2025-11-04T13:37:05","slug":"colisao-entre-veiculos-deixa-mulher-ferida-no-centro-de-corumba","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/colisao-entre-veiculos-deixa-mulher-ferida-no-centro-de-corumba\/","title":{"rendered":"Colis\u00e3o entre ve\u00edculos deixa mulher ferida no centro de Corumb\u00e1"},"content":{"rendered":"\n<p>Uma mulher de 64 anos ficou ferida em um acidente envolvendo dois ve\u00edculos na manh\u00e3 desta segunda-feira (3), no cruzamento das ruas Firmo de Matos e Colombo, regi\u00e3o central de Corumb\u00e1.<br><br>O Corpo de Bombeiros Militar foi acionado por volta das 10h35 e encontrou a v\u00edtima dentro de um dos carros (Renault Duster), consciente e orientada, mas com dores no t\u00f3rax e no tornozelo direito. Ela recebeu atendimento pr\u00e9-hospitalar no local, sendo imobilizada e estabilizada antes do transporte.<br><br>No mesmo ve\u00edculo tamb\u00e9m estava o neto da mulher, um menino de 7 anos, que sofreu apenas escoria\u00e7\u00f5es leves na perna direita.<br><br>As duas v\u00edtimas foram levadas ao Pronto-Socorro Municipal para avalia\u00e7\u00e3o e cuidados m\u00e9dicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma mulher de 64 anos ficou ferida em um acidente envolvendo dois ve\u00edculos na manh\u00e3&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11775531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-11775525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguranca"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11775525"}],"version-history":[{"count":4,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775525\/revisions"}],"predecessor-version":[{"id":11775533,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775525\/revisions\/11775533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11775531"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11775525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11775525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11775525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}