{"id":11775877,"date":"2025-11-12T10:15:00","date_gmt":"2025-11-12T14:15:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11775877"},"modified":"2025-11-12T10:13:30","modified_gmt":"2025-11-12T14:13:30","slug":"acidente-entre-carro-e-moto-mobiliza-bombeiros-no-centro-de-corumba","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/acidente-entre-carro-e-moto-mobiliza-bombeiros-no-centro-de-corumba\/","title":{"rendered":"Acidente entre carro e moto mobiliza Bombeiros no centro de Corumb\u00e1"},"content":{"rendered":"<p>O Corpo de Bombeiros Militar de Mato Grosso do Sul, por meio do 3\u00ba Grupamento de Bombeiros Militar, registrou cinco ocorr\u00eancias nas \u00faltimas 24 horas em Corumb\u00e1. Entre elas, um acidente de tr\u00e2nsito mobilizou as guarni\u00e7\u00f5es por volta das 13h30 desta ter\u00e7a-feira (11), no cruzamento da rua Sete de Setembro com a rua Joaquim Venceslau de Barros, na \u00e1rea central.<\/p>\n<p>A colis\u00e3o envolveu uma motocicleta Honda Biz 125, de cor vermelha, conduzida por uma mulher de 25 anos, e um ve\u00edculo GM Montana Conquest, branco, dirigido por um homem de 42 anos. A motociclista sofreu escoria\u00e7\u00f5es no joelho esquerdo, p\u00e9 direito, cotovelo direito e m\u00e3o direita, al\u00e9m de uma pancada na cabe\u00e7a, relatando dores intensas.<\/p>\n<p>As equipes das viaturas UR-153 e ABTF-04 realizaram atendimento pr\u00e9-hospitalar, com curativos e imobiliza\u00e7\u00e3o, encaminhando a v\u00edtima consciente e orientada ao Pronto-Socorro de Corumb\u00e1 para avalia\u00e7\u00e3o m\u00e9dica e exames complementares. O condutor do carro n\u00e3o sofreu ferimentos.<\/p>\n<p>Ap\u00f3s o socorro, o local ficou sob responsabilidade da Pol\u00edcia Militar, que adotou os procedimentos administrativos cab\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Corpo de Bombeiros Militar de Mato Grosso do Sul, por meio do 3\u00ba Grupamento&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11772725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[249],"class_list":["post-11775877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguranca","tag-seguranca"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11775877"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775877\/revisions"}],"predecessor-version":[{"id":11775878,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11775877\/revisions\/11775878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11772725"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11775877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11775877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11775877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}