{"id":11776044,"date":"2025-11-17T16:20:00","date_gmt":"2025-11-17T20:20:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11776044"},"modified":"2025-11-17T18:11:47","modified_gmt":"2025-11-17T22:11:47","slug":"do-ar-para-a-terra-escola-estadual-de-ms-transforma-agua-de-ar-condicionado-em-alfaces-sustentaveis","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/do-ar-para-a-terra-escola-estadual-de-ms-transforma-agua-de-ar-condicionado-em-alfaces-sustentaveis\/","title":{"rendered":"Do ar para a terra: escola estadual de MS transforma \u00e1gua de ar-condicionado em alfaces sustent\u00e1veis"},"content":{"rendered":"<p>Ao unir tecnologia, sustentabilidade e aprendizado pr\u00e1tico em um mesmo espa\u00e7o verde, a Escola Estadual Professora Neyder Suelly se destaca como refer\u00eancia em Campo Grande. O projeto de horta escolar sustent\u00e1vel, desenvolvido por alunos e professores, introduziu um sistema inovador de hidroponia &#8211; t\u00e9cnica que permite o cultivo de hortali\u00e7as sem solo &#8211; utilizando \u00e1gua reaproveitada dos aparelhos de ar-condicionado.<\/p>\n<p>A proposta nasceu com o objetivo de reduzir o desperd\u00edcio e promover a Educa\u00e7\u00e3o Ambiental de forma vivencial. Desde o preparo das mudas at\u00e9 a colheita, os estudantes participam de todas as etapas do processo, desenvolvendo responsabilidade, senso de pertencimento e consci\u00eancia ecol\u00f3gica.<\/p>\n<p>O professor H\u00e9lio Alves da Silva, respons\u00e1vel pelo projeto de hidroponia, explicou como funciona o processo de reaproveitamento da \u00e1gua.<\/p>\n<p>\u201cColetamos a \u00e1gua de quatro aparelhos e armazenamos em uma caixa de 310 litros. Ela recebe tratamento com nutrientes e tem o pH e o PPM controlados para garantir o crescimento das plantas. Cada ar-condicionado produz de 18 a 25 litros por dia, e a reposi\u00e7\u00e3o \u00e9 feita cerca de uma vez por semana. Vamos enviar amostras para an\u00e1lise e, com apoio do Bioparque, ampliar o projeto para a cria\u00e7\u00e3o de peixes junto \u00e0s hortali\u00e7as\u201d, detalhou o educador.<\/p>\n<div id=\"gallery-1\" class=\"gallery galleryid-526743 gallery-columns-2 gallery-size-large\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-9-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-4-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-1-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-10-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<\/div>\n<p>O aluno Caleb Gattes Roberto de Oliveira, de 13 anos, estudante do 8\u00ba ano, participa ativamente do projeto, refor\u00e7ou a import\u00e2ncia da iniciativa.<\/p>\n<p>\u201cEu gosto de participar de projetos e achei essa ideia muito boa, porque evita o desperd\u00edcio de \u00e1gua. Como usamos bastante, decidimos reutilizar a \u00e1gua do ar-condicionado na hidroponia. \u00c9 importante para a sustentabilidade, j\u00e1 que reaproveitamos o que seria descartado\u201d, destacou o estudante.<\/p>\n<p>A horta tamb\u00e9m \u00e9 um exemplo de interdisciplinaridade em a\u00e7\u00e3o. Alunos de Administra\u00e7\u00e3o cuidam da gest\u00e3o de custos e insumos, os de Publicidade produzem materiais de divulga\u00e7\u00e3o, e o Clube de Ci\u00eancias monitora a qualidade da \u00e1gua no laborat\u00f3rio, aplicando conhecimentos de qu\u00edmica e biologia em um contexto pr\u00e1tico e integrado.<\/p>\n<p>Para o diretor M\u00e1rcio Wagner, o projeto representa a consolida\u00e7\u00e3o de um trabalho coletivo que une aprendizado e compromisso ambiental.<\/p>\n<p>\u201cA escola j\u00e1 trabalha h\u00e1 algum tempo com a educa\u00e7\u00e3o sustent\u00e1vel. Recentemente, fomos ao Rio de Janeiro receber o Selo ODS, como uma das duas escolas do estado certificadas. Isso nos motivou a ampliar ainda mais nossas a\u00e7\u00f5es. A entrega das mudas \u00e0 comunidade \u00e9 uma forma de divulgar nosso trabalho e refor\u00e7ar nosso compromisso ambiental. Se estamos fazendo algo bom, precisamos mostrar isso \u00e0 sociedade\u201d, finalizou o diretor.<\/p>\n<div id=\"gallery-2\" class=\"gallery galleryid-526743 gallery-columns-3 gallery-size-large\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-1024x683.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-1024x683.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-300x200.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-768x512.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-1536x1024.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-2048x1365.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-350x232.jpg 350w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-15-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"683\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-1024x683.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-1024x683.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-300x200.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-768x512.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-1536x1024.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-2048x1365.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-350x232.jpg 350w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-14-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"683\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-1024x683.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-1024x683.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-300x200.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-768x512.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-1536x1024.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-2048x1365.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-350x232.jpg 350w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-13-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"683\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-12-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-6-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-11-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-3-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-2-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-1024x768.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-1024x768.jpg 1024w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-300x225.jpg 300w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-768x576.jpg 768w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-1536x1152.jpg 1536w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-2048x1536.jpg 2048w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-320x240.jpg 320w, https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2025\/11\/Horta-Hidroponica-Escola-Estadual-Foto-Cid-Nogueira-SED-8-scaled.jpg 1920w\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/figure>\n<\/div>\n<p>O projeto \u00e9 uma prova de que a inova\u00e7\u00e3o e o cuidado com o planeta podem nascer dentro da sala de aula. Com criatividade, ci\u00eancia e consci\u00eancia ambiental, at\u00e9 a \u00e1gua que antes se perdia no ar agora ajuda a cultivar um futuro mais verde e sustent\u00e1vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao unir tecnologia, sustentabilidade e aprendizado pr\u00e1tico em um mesmo espa\u00e7o verde, a Escola Estadual&#8230;<\/p>\n","protected":false},"author":13,"featured_media":11776045,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[209],"class_list":["post-11776044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meio-ambiente","tag-meio-ambiente"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11776044"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776044\/revisions"}],"predecessor-version":[{"id":11776046,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776044\/revisions\/11776046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11776045"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11776044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11776044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11776044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}