{"id":11776073,"date":"2025-11-18T13:00:00","date_gmt":"2025-11-18T17:00:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11776073"},"modified":"2025-11-18T14:03:19","modified_gmt":"2025-11-18T18:03:19","slug":"habilitado-para-captar-recursos-de-redd-ms-vai-estruturar-mercado-de-carbono-a-partir-de-2026","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/habilitado-para-captar-recursos-de-redd-ms-vai-estruturar-mercado-de-carbono-a-partir-de-2026\/","title":{"rendered":"Habilitado para captar recursos de REDD+, MS vai estruturar mercado de carbono a partir de 2026"},"content":{"rendered":"<p>Mato Grosso do Sul d\u00e1 mais um passo decisivo em sua estrat\u00e9gia de descarboniza\u00e7\u00e3o e fortalecimento da economia verde. Foi publicada ontem (17) no Di\u00e1rio Oficial da Uni\u00e3o a\u00a0<a href=\"https:\/\/www.in.gov.br\/web\/dou\/-\/resolucao-n-20-de-14-de-outubro-de-2025-669280327\" target=\"_blank\" rel=\"noopener\">Resolu\u00e7\u00e3o n\u00ba 20\/2025 da Comiss\u00e3o Nacional para REDD+ (CONAREDD+)<\/a>,\u00a0que aprova a elegibilidade do Estado para acessar e captar pagamentos por resultados de REDD+ no bioma Cerrado.<\/p>\n<p>A partir da publica\u00e7\u00e3o, a Semadesc (Secretaria de Meio Ambiente, Desenvolvimento, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o) passa a ser oficialmente a respons\u00e1vel pela capta\u00e7\u00e3o e condu\u00e7\u00e3o dos processos de certifica\u00e7\u00e3o e comercializa\u00e7\u00e3o dos cr\u00e9ditos no territ\u00f3rio sul-mato-grossense.<\/p>\n<p>O reconhecimento do governo federal confirma que Mato Grosso do Sul atende aos crit\u00e9rios t\u00e9cnicos, jur\u00eddicos e de governan\u00e7a exigidos pelo mecanismo internacional de Redu\u00e7\u00e3o de Emiss\u00f5es por Desmatamento e Degrada\u00e7\u00e3o Florestal, vinculado \u00e0 Conven\u00e7\u00e3o-Quadro das Na\u00e7\u00f5es Unidas sobre Mudan\u00e7a do Clima (UNFCCC).<\/p>\n<p>Na pr\u00e1tica, isso abre caminho para que o Estado acesse recursos internacionais destinados \u00e0 conserva\u00e7\u00e3o florestal e ao combate \u00e0s emiss\u00f5es.<\/p>\n<p>&#8220;Essa \u00e9 a confirma\u00e7\u00e3o de que Mato Grosso do Sul consolidou um modelo de governan\u00e7a ambiental robusto, transparente e alinhado \u00e0s melhores pr\u00e1ticas internacionais. Essa elegibilidade mostra que o Estado est\u00e1 preparado para acessar mecanismos financeiros globais e transformar a conserva\u00e7\u00e3o das nossas florestas em oportunidade real de desenvolvimento sustent\u00e1vel. \u00c9 um passo hist\u00f3rico que fortalece nossa estrat\u00e9gia de descarboniza\u00e7\u00e3o&#8221;, afirma o secret\u00e1rio Jaime Verruck, da Semadesc.<\/p>\n<p>Secret\u00e1rio-adjunto, Artur Falcette refor\u00e7ou que a elegibilidade cobre o volume de emiss\u00f5es evitadas no Cerrado e d\u00e1 origem a um potencial expressivo de cr\u00e9ditos.<\/p>\n<p>&#8220;Estamos falando de um estoque relevante que agora poder\u00e1 passar pelos processos de verifica\u00e7\u00e3o, certifica\u00e7\u00e3o e posterior comercializa\u00e7\u00e3o. O pr\u00f3ximo passo \u00e9 justamente estruturar esse pipeline junto ao mercado, sempre com transpar\u00eancia e reparti\u00e7\u00e3o de benef\u00edcios&#8221;, avaliou.<\/p>\n<p><strong>Edital ser\u00e1 lan\u00e7ado em janeiro de 2026<\/strong><\/p>\n<p>Durante sua passagem pela COP 30, em Bel\u00e9m, o governador Eduardo Riedel anunciou que em janeiro de 2026 ser\u00e1 lan\u00e7ado edital de Chamamento P\u00fablico para a apresenta\u00e7\u00e3o de propostas de oportunidades de neg\u00f3cios relacionadas \u00e0 estrutura\u00e7\u00e3o, desenvolvimento, monitoramento, verifica\u00e7\u00e3o, certifica\u00e7\u00e3o e comercializa\u00e7\u00e3o de cr\u00e9ditos de carbono no \u00e2mbito do REDD+ bioma Cerrado em Mato Grosso do Sul. O edital ser\u00e1 publicado pela Semadesc.<\/p>\n<p>O an\u00fancio foi feito ao lado do secret\u00e1rio Jaime Verruck e do secret\u00e1rio adjunto Artur Falcette, refor\u00e7ando a diretriz de que o Estado n\u00e3o apenas cumprir\u00e1 as exig\u00eancias do mecanismo internacional, mas tamb\u00e9m organizar\u00e1 seu mercado de carbono com base em governan\u00e7a, seguran\u00e7a jur\u00eddica e ampla participa\u00e7\u00e3o de parceiros especializados.<\/p>\n<p>Na submiss\u00e3o ao CONAREDD+, Mato Grosso do Sul demonstrou redu\u00e7\u00e3o consistente das emiss\u00f5es por desmatamento e a exist\u00eancia de pol\u00edticas p\u00fablicas, sistemas de monitoramento e salvaguardas socioambientais consolidados.<\/p>\n<p>O territ\u00f3rio sul-mato-grossense \u00e9 formado em 62,2% de Cerrado, 27,3% de Pantanal e 10,5% de Mata Atl\u00e2ntica, com mais de 110 mil km\u00b2 de vegeta\u00e7\u00e3o nativa remanescente.<\/p>\n<p>&#8220;Agora, com a elegibilidade reconhecida e o edital anunciado, Mato Grosso do Sul consolida sua transi\u00e7\u00e3o para um modelo de desenvolvimento baseado em conserva\u00e7\u00e3o, tecnologia e gera\u00e7\u00e3o de valor ambiental, aproximando-se da meta de se tornar territ\u00f3rio carbono neutro at\u00e9 2030&#8221;, finalizou o secret\u00e1rio Jaime Verruck.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mato Grosso do Sul d\u00e1 mais um passo decisivo em sua estrat\u00e9gia de descarboniza\u00e7\u00e3o e&#8230;<\/p>\n","protected":false},"author":13,"featured_media":11776074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,17],"tags":[189,209],"class_list":["post-11776073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-meio-ambiente","tag-economia","tag-meio-ambiente"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11776073"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776073\/revisions"}],"predecessor-version":[{"id":11776075,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776073\/revisions\/11776075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11776074"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11776073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11776073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11776073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}