{"id":11776123,"date":"2025-11-19T10:35:00","date_gmt":"2025-11-19T14:35:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11776123"},"modified":"2025-11-19T11:06:08","modified_gmt":"2025-11-19T15:06:08","slug":"corpo-de-bombeiros-atende-jovem-em-estado-grave-apos-acidente-de-bicicleta","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/corpo-de-bombeiros-atende-jovem-em-estado-grave-apos-acidente-de-bicicleta\/","title":{"rendered":"Corpo de Bombeiros atende jovem em estado grave ap\u00f3s acidente de bicicleta"},"content":{"rendered":"<p>Por volta de meia-noite, o Corpo de Bombeiros Militar foi acionado para atender uma ocorr\u00eancia de queda acidental no cruzamento das ruas XV de Novembro e Paran\u00e1.<\/p>\n<p>No local, a guarni\u00e7\u00e3o encontrou um adolescente de 15 anos que havia ca\u00eddo de bicicleta e batido a cabe\u00e7a contra o solo. A v\u00edtima apresentava quadro preocupante: crise convulsiva, estado de inconsci\u00eancia, epis\u00f3dios de v\u00f4mito e pupilas dilatadas , sinais compat\u00edveis com poss\u00edvel traumatismo craniano.<\/p>\n<p>Diante da gravidade, a equipe realizou o atendimento emergencial e estabiliza\u00e7\u00e3o inicial, procedendo com o r\u00e1pido transporte ao pronto-socorro municipal, onde o adolescente foi entregue aos cuidados da equipe m\u00e9dica de plant\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta de meia-noite, o Corpo de Bombeiros Militar foi acionado para atender uma ocorr\u00eancia&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11772725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[249],"class_list":["post-11776123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguranca","tag-seguranca"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11776123"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776123\/revisions"}],"predecessor-version":[{"id":11776124,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776123\/revisions\/11776124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11772725"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11776123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11776123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11776123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}