{"id":11776211,"date":"2025-11-24T10:04:00","date_gmt":"2025-11-24T14:04:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11776211"},"modified":"2025-11-24T11:34:11","modified_gmt":"2025-11-24T15:34:11","slug":"prf-recupera-veiculo-com-registro-de-furto-na-br-262","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/prf-recupera-veiculo-com-registro-de-furto-na-br-262\/","title":{"rendered":"PRF recupera ve\u00edculo com registro de furto na BR-262"},"content":{"rendered":"<p dir=\"ltr\">A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) recuperou um ve\u00edculo, neste s\u00e1bado (22), em \u00c1gua Clara.<\/p>\n<p dir=\"ltr\">Durante fiscaliza\u00e7\u00f5es na BR-262, os policiais abordaram uma Fiat\/Strada e ap\u00f3s vistoria no ve\u00edculo descobriram que a picape possu\u00eda registro de furto, em Sorocaba (SP), desde outubro de 2025.<\/p>\n<p dir=\"ltr\">O motorista, que viajava com uma mulher e dois menores de idade, disse que teria adquirido o ve\u00edculo em Corumb\u00e1 e viajaria at\u00e9 o interior de S\u00e3o Paulo.<\/p>\n<p dir=\"ltr\">A ocorr\u00eancia foi encaminhada \u00e0 Pol\u00edcia Civil em \u00c1gua Clara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) recuperou um ve\u00edculo, neste s\u00e1bado (22), em \u00c1gua Clara. Durante&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11776212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[249],"class_list":["post-11776211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguranca","tag-seguranca"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11776211"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776211\/revisions"}],"predecessor-version":[{"id":11776213,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776211\/revisions\/11776213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11776212"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11776211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11776211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11776211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}