{"id":11776295,"date":"2025-11-26T08:38:00","date_gmt":"2025-11-26T12:38:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11776295"},"modified":"2025-11-26T08:51:35","modified_gmt":"2025-11-26T12:51:35","slug":"adolescente-e-arrastado-pela-correnteza-no-rio-paraguai-e-continua-desaparecido","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/adolescente-e-arrastado-pela-correnteza-no-rio-paraguai-e-continua-desaparecido\/","title":{"rendered":"Adolescente \u00e9 arrastado pela correnteza no Rio Paraguai e continua desaparecido"},"content":{"rendered":"<p>Nas \u00faltimas 24 horas, a Central de Opera\u00e7\u00f5es do 3\u00b0 Grupamento de Bombeiros Militar em Corumb\u00e1 teve cinco ocorr\u00eancias atendidas pela guarni\u00e7\u00e3o de prontid\u00e3o. No final da tarde e in\u00edcio da noite de ontem (25), o Corpo de Bombeiros Militar foi acionado para atender uma situa\u00e7\u00e3o de poss\u00edvel afogamento no rio Paraguai, em uma \u00e1rea pr\u00f3xima \u00e0 antiga Olaria, conhecida como Porto do Raul, nas proximidades do Bairro Borrowski.<\/p>\n<p>De acordo com relatos de moradores que estavam no local, um jovem de 18 anos tomava banho no rio quando acabou submergindo e n\u00e3o retornou \u00e0 superf\u00edcie. A v\u00edtima encontrava-se cerca de 30 metros para dentro do rio e, mesmo ap\u00f3s ser alertada sobre a profundidade e a forte correnteza, permaneceu no local. Momentos depois, teria sido arrastada pela correnteza, vindo a se afogar.<\/p>\n<p>A equipe de mergulho realizou buscas entre 19h e 21h, atingindo cerca de 5 metros de profundidade e atuando aproximadamente 50 metros da margem direita do Rio Paraguai. Apesar dos esfor\u00e7os, o jovem ainda n\u00e3o foi localizado.<\/p>\n<p>As buscas continuam em andamento, seguindo o protocolo operacional do Corpo de Bombeiros Militar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nas \u00faltimas 24 horas, a Central de Opera\u00e7\u00f5es do 3\u00b0 Grupamento de Bombeiros Militar em&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11776296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[249],"class_list":["post-11776295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguranca","tag-seguranca"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11776295"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776295\/revisions"}],"predecessor-version":[{"id":11776297,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776295\/revisions\/11776297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11776296"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11776295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11776295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11776295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}