{"id":11776406,"date":"2025-11-28T08:10:00","date_gmt":"2025-11-28T12:10:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11776406"},"modified":"2025-11-28T09:00:19","modified_gmt":"2025-11-28T13:00:19","slug":"caixa-conclui-pagamento-da-parcela-de-novembro-do-bolsa-familia","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/caixa-conclui-pagamento-da-parcela-de-novembro-do-bolsa-familia\/","title":{"rendered":"Caixa conclui pagamento da parcela de novembro do Bolsa Fam\u00edlia\u00a0"},"content":{"rendered":"<p>A Caixa Econ\u00f4mica Federal conclui o pagamento da parcela de novembro do Bolsa Fam\u00edlia. Recebem nesta sexta-feira (28) os benefici\u00e1rios com N\u00famero de Inscri\u00e7\u00e3o Social (NIS) de final 0.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1669998&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1669998&amp;o=node\" \/><\/p>\n<p>O valor m\u00ednimo corresponde a R$ 600, mas com o novo adicional o valor m\u00e9dio do benef\u00edcio sobe para R$ 683,28. Segundo o Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, neste m\u00eas o programa de transfer\u00eancia de renda do governo federal alcan\u00e7ou 18,65 milh\u00f5es de fam\u00edlias, com gasto de R$ 12,69 bilh\u00f5es.<\/p>\n<p>Al\u00e9m do benef\u00edcio m\u00ednimo, h\u00e1 o pagamento de tr\u00eas adicionais. O Benef\u00edcio Vari\u00e1vel Familiar Nutriz paga seis parcelas de R$ 50 a m\u00e3es de beb\u00eas de at\u00e9 seis meses de idade, para garantir a alimenta\u00e7\u00e3o da crian\u00e7a. O Bolsa Fam\u00edlia tamb\u00e9m paga um acr\u00e9scimo de R$ 50 a gestantes e nutrizes (m\u00e3es que amamentam), um de R$ 50 a cada filho de 7 a 18 anos e outro, de R$ 150, a cada crian\u00e7a de at\u00e9 6 anos.<\/p>\n<p>No modelo tradicional do Bolsa Fam\u00edlia, o pagamento ocorre nos \u00faltimos dez dias \u00fateis de cada m\u00eas. O benefici\u00e1rio pode\u00a0consultar informa\u00e7\u00f5es sobre as datas de pagamento, o valor do benef\u00edcio e a composi\u00e7\u00e3o das parcelas no aplicativo Caixa Tem, usado para acompanhar as contas poupan\u00e7a digitais do banco.<\/p>\n<h2>Pagamento unificado<\/h2>\n<p>Os benefici\u00e1rios de 735 cidades receberam o pagamento no \u00faltimo dia 14, independentemente do NIS. A medida beneficiou os moradores dos 497 munic\u00edpios do Rio Grande do Sul e de todos os 22 munic\u00edpios do Acre. Tamb\u00e9m foram beneficiadas cidades em sete estados: Rio Grande do Norte (147), Paran\u00e1 (38), Sergipe (9), S\u00e3o Paulo (7), Piau\u00ed (6), Roraima (6) e Amazonas (3).\u00a0Entre as cidades paranaenses com pagamento unificado, est\u00e1\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2025-11\/parana-confirma-setima-morte-causada-por-tornados-simultaneos\" target=\"_blank\" rel=\"noopener\">Rio Bonito do Igua\u00e7u<\/a>, que teve 90% das constru\u00e7\u00f5es destru\u00eddas por um tornado.<\/p>\n<p>Essas localidades foram afetadas por chuvas ou por estiagens ou t\u00eam povos ind\u00edgenas em situa\u00e7\u00e3o de vulnerabilidade. A\u00a0<a href=\"https:\/\/www.gov.br\/mds\/pt-br\/noticias-e-conteudos\/desenvolvimento-social\/noticias-desenvolvimento-social\/bolsa-familia-pagamento-unificado-ira-beneficiar-mais-de-um-milhao-de-familias-em-novembro\" target=\"_blank\" rel=\"noopener\">lista dos munic\u00edpios com pagamento antecipado<\/a>\u00a0est\u00e1 dispon\u00edvel na p\u00e1gina do Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social.<\/p>\n<p>Desde o ano passado, os benefici\u00e1rios do Bolsa Fam\u00edlia n\u00e3o t\u00eam mais o desconto do Seguro Defeso. A mudan\u00e7a foi estabelecida pela\u00a0<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2023-2026\/2023\/lei\/l14601.htm\" target=\"_blank\" rel=\"noopener\">Lei 14.601\/2023<\/a>, que resgatou o Programa Bolsa Fam\u00edlia (PBF). O Seguro Defeso \u00e9 pago a pessoas que sobrevivem exclusivamente da pesca artesanal e que n\u00e3o podem exercer a atividade durante o per\u00edodo da piracema (reprodu\u00e7\u00e3o dos peixes).<\/p>\n<h2>Regra de prote\u00e7\u00e3o<\/h2>\n<p>Cerca de 2,42 milh\u00f5es de fam\u00edlias est\u00e3o na regra de prote\u00e7\u00e3o em novembro. Essa regra permite que fam\u00edlias cujos membros consigam emprego e melhorem a renda recebam 50% do benef\u00edcio a que teriam direito por at\u00e9 dois anos, desde que cada integrante receba o equivalente a at\u00e9 meio sal\u00e1rio m\u00ednimo.<\/p>\n<p>Em junho, o tempo de perman\u00eancia na\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-05\/governo-altera-regra-de-transicao-do-bolsa-familia-entenda\" target=\"_blank\" rel=\"noopener\">regra de prote\u00e7\u00e3o<\/a>\u00a0foi reduzido de dois para um ano. No entanto, a mudan\u00e7a s\u00f3 abrange as fam\u00edlias que entraram na fase de transi\u00e7\u00e3o desde junho. Quem se enquadrou na regra at\u00e9 maio deste ano continuar\u00e1 a receber metade do benef\u00edcio por dois anos.<\/p>\n<h2>Aux\u00edlio G\u00e1s<\/h2>\n<p>Neste m\u00eas n\u00e3o houve o pagamento do Aux\u00edlio G\u00e1s, que beneficia fam\u00edlias inscritas no Cad\u00danico.\u00a0Como o benef\u00edcio s\u00f3 \u00e9 pago a cada dois meses, ele\u00a0voltar\u00e1 em dezembro.<\/p>\n<p>S\u00f3 pode receber o Aux\u00edlio G\u00e1s quem est\u00e1 inclu\u00eddo no Cad\u00danico e tenha pelo menos um membro da fam\u00edlia que receba o Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC). A lei que criou o programa definiu que a mulher respons\u00e1vel pela fam\u00edlia ter\u00e1 prefer\u00eancia, assim como mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Caixa Econ\u00f4mica Federal conclui o pagamento da parcela de novembro do Bolsa Fam\u00edlia. Recebem&#8230;<\/p>\n","protected":false},"author":4,"featured_media":11764686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[189],"class_list":["post-11776406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-economia"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11776406"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776406\/revisions"}],"predecessor-version":[{"id":11776407,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11776406\/revisions\/11776407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11764686"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11776406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11776406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11776406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}