{"id":11781717,"date":"2026-05-12T08:48:00","date_gmt":"2026-05-12T12:48:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11781717"},"modified":"2026-05-12T09:14:24","modified_gmt":"2026-05-12T13:14:24","slug":"mega-sena-sorteia-premio-de-r-52-milhoes-nesta-terca-feira","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/mega-sena-sorteia-premio-de-r-52-milhoes-nesta-terca-feira\/","title":{"rendered":"Mega-Sena sorteia pr\u00eamio de R$ 52 milh\u00f5es nesta ter\u00e7a-feira"},"content":{"rendered":"<p>As seis dezenas do concurso 3.007 da Mega-Sena ser\u00e3o sorteadas, a partir das 21h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o da Sorte, localizado na Avenida Paulista, n\u00ba 750, em S\u00e3o Paulo.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1689077&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1689077&amp;o=node\" \/><\/p>\n<p>O pr\u00eamio da faixa principal est\u00e1 acumulado em R$ 52 milh\u00f5es.<\/p>\n<p>O sorteio ter\u00e1 transmiss\u00e3o ao vivo pelo\u00a0<a href=\"https:\/\/www.youtube.com\/@canalcaixa\" target=\"_blank\" rel=\"noopener\">canal da Caixa no YouTube<\/a>\u00a0e no Facebook das Loterias Caixa.<\/p>\n<p>As apostas podem ser feitas at\u00e9 as 20h (hor\u00e1rio de Bras\u00edlia), nas lot\u00e9ricas em todo o pa\u00eds ou pela internet, no\u00a0<a href=\"https:\/\/loterias.caixa.gov.br\/Paginas\/default.aspx\" target=\"_blank\" rel=\"noopener\">site\u00a0das Loterias da Caixa<\/a>\u00a0e pelo aplicativo Caixa.<\/p>\n<p>O jogo simples, com seis n\u00fameros marcados, custa R$ 6.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As seis dezenas do concurso 3.007 da Mega-Sena ser\u00e3o sorteadas, a partir das 21h (hor\u00e1rio&#8230;<\/p>\n","protected":false},"author":4,"featured_media":11738125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[235],"tags":[187],"class_list":["post-11781717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-loterias","tag-mega-sena"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11781717"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781717\/revisions"}],"predecessor-version":[{"id":11781718,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781717\/revisions\/11781718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11738125"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11781717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11781717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11781717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}