{"id":11781719,"date":"2026-05-12T09:03:00","date_gmt":"2026-05-12T13:03:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11781719"},"modified":"2026-05-12T09:15:47","modified_gmt":"2026-05-12T13:15:47","slug":"assistencia-social-reune-profissionais-da-rede-de-protecao-em-acao-alusiva-ao-maio-laranja","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/assistencia-social-reune-profissionais-da-rede-de-protecao-em-acao-alusiva-ao-maio-laranja\/","title":{"rendered":"Assist\u00eancia Social re\u00fane profissionais da rede de prote\u00e7\u00e3o em a\u00e7\u00e3o alusiva ao Maio Laranja"},"content":{"rendered":"<p>A Prefeitura de Corumb\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social e Cidadania (SMASC), promoveu nesta segunda-feira (11) um encontro voltado aos profissionais da rede socioassistencial do munic\u00edpio, em alus\u00e3o \u00e0 Campanha Maio Laranja.<\/p>\n<p>Realizado no CRAS I, o momento reuniu t\u00e9cnicos, orientadores e representantes de diferentes equipamentos e servi\u00e7os da assist\u00eancia social, entre eles os CRAS, CREAS, Centro de Conviv\u00eancia do Idoso (CCI) e Casa do Imigrante, com o objetivo de fortalecer as a\u00e7\u00f5es de preven\u00e7\u00e3o e conscientiza\u00e7\u00e3o relacionadas ao enfrentamento da viol\u00eancia sexual contra crian\u00e7as e adolescentes.<\/p>\n<p>Durante o encontro, os participantes vivenciaram din\u00e2micas, estudos de casos e momentos de troca de experi\u00eancias, promovendo reflex\u00f5es sobre a atua\u00e7\u00e3o da rede diante de situa\u00e7\u00f5es de viola\u00e7\u00e3o de direitos. A proposta tamb\u00e9m buscou alinhar estrat\u00e9gias e atividades que ser\u00e3o desenvolvidas junto aos usu\u00e1rios dos servi\u00e7os ao longo do m\u00eas de maio.<\/p>\n<p>A campanha Maio Laranja \u00e9 uma mobiliza\u00e7\u00e3o nacional de combate ao abuso e \u00e0 explora\u00e7\u00e3o sexual de crian\u00e7as e adolescentes e refor\u00e7a a import\u00e2ncia da informa\u00e7\u00e3o, da preven\u00e7\u00e3o e da atua\u00e7\u00e3o integrada entre os servi\u00e7os p\u00fablicos, escolas, fam\u00edlias e sociedade civil. A data faz refer\u00eancia ao 18 de Maio, Dia Nacional de Combate ao Abuso e \u00e0 Explora\u00e7\u00e3o Sexual de Crian\u00e7as e Adolescentes, institu\u00eddo para conscientizar a popula\u00e7\u00e3o sobre a necessidade de proteger crian\u00e7as e adolescentes de toda forma de viol\u00eancia.<\/p>\n<p>Al\u00e9m do conte\u00fado t\u00e9cnico e reflexivo, o encontro proporcionou um espa\u00e7o de escuta, fortalecimento e integra\u00e7\u00e3o entre os profissionais que atuam diretamente nos territ\u00f3rios, contribuindo para um atendimento mais humanizado, atento e preparado para identificar sinais de viol\u00eancia e acolher situa\u00e7\u00f5es de vulnerabilidade.<\/p>\n<p>A Secretaria Municipal de Assist\u00eancia Social e Cidadania destacou que momentos como esse fortalecem a rede de prote\u00e7\u00e3o e reafirmam o compromisso coletivo na garantia dos direitos das crian\u00e7as e adolescentes em Corumb\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Corumb\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social e Cidadania (SMASC),&#8230;<\/p>\n","protected":false},"author":70,"featured_media":11781720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-11781719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11781719"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781719\/revisions"}],"predecessor-version":[{"id":11781721,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781719\/revisions\/11781721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11781720"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11781719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11781719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11781719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}