{"id":11781722,"date":"2026-05-12T09:17:00","date_gmt":"2026-05-12T13:17:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11781722"},"modified":"2026-05-12T09:28:28","modified_gmt":"2026-05-12T13:28:28","slug":"auditor-reforca-importancia-de-destinar-parte-do-imposto-de-renda-a-instituicoes-assistenciais","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/auditor-reforca-importancia-de-destinar-parte-do-imposto-de-renda-a-instituicoes-assistenciais\/","title":{"rendered":"Auditor refor\u00e7a import\u00e2ncia de destinar parte do Imposto de Renda a institui\u00e7\u00f5es assistenciais"},"content":{"rendered":"<p>Destinar parte do Imposto de Renda a institui\u00e7\u00f5es assistenciais \u00e9 um exerc\u00edcio de cidadania que permite direcionar recursos para causas sociais sem custo adicional ao contribuinte. Pela legisla\u00e7\u00e3o, pessoas f\u00edsicas podem destinar at\u00e9 6% do imposto devido, fortalecendo iniciativas locais e ampliando o financiamento de projetos voltados a p\u00fablicos em situa\u00e7\u00e3o de vulnerabilidade.<\/p>\n<p>O tema foi abordado na noite de ontem, segunda-feira, 11, durante sess\u00e3o ordin\u00e1ria da C\u00e2mara Municipal, pelo auditor da Receita Federal em Corumb\u00e1, Maur\u00edcio Pereira Goulart, que utilizou a tribuna a convite do vereador Jovan Temeljkovitch.<\/p>\n<p>A participa\u00e7\u00e3o na sess\u00e3o permitiu detalhar a campanha \u201cEu Sou Cidad\u00e3o Solid\u00e1rio\u201d, promovida pela Receita Federal do Brasil, que incentiva a destina\u00e7\u00e3o de parte do Imposto de Renda para iniciativas voltadas a crian\u00e7as e adolescentes, pessoas idosas e, ainda, a projetos culturais, audiovisuais e esportivos.<\/p>\n<p>O auditor lembrou que o prazo para entrega da declara\u00e7\u00e3o vai at\u00e9 29 de maio e conclamou vereadores e popula\u00e7\u00e3o a aderirem \u00e0 campanha, ampliando o volume de recursos destinados a quem mais necessita.<\/p>\n<p>Maur\u00edcio tamb\u00e9m ressaltou a import\u00e2ncia de direcionar parte do imposto devido a entidades sociais do munic\u00edpio que prestam servi\u00e7os essenciais, de modo a assegurar que os recursos sejam aplicados com maior agilidade na pr\u00f3pria comunidade.<\/p>\n<p>Segundo ele, em Corumb\u00e1, cerca de 9,3 mil contribuintes estariam aptos a participar da campanha, o que poderia resultar em arrecada\u00e7\u00e3o aproximada de R$ 9,3 milh\u00f5es. O montante \u00e9 significativamente superior ao registrado nos dois \u00faltimos anos: R$ 71 mil em 2024 e R$ 180 mil em 2025.<\/p>\n<p>A campanha \u201cEu Sou Cidad\u00e3o Solid\u00e1rio\u201d, da Receita Federal, incentiva a destina\u00e7\u00e3o de at\u00e9 6% do Imposto de Renda devido \u2014 sendo 3% para fundos da crian\u00e7a e do adolescente e 3% para fundos da pessoa idosa \u2014 diretamente na declara\u00e7\u00e3o. A iniciativa \u00e9 segura, n\u00e3o gera custo adicional ao contribuinte e direciona recursos para projetos sociais locais, podendo ser realizada no modelo completo da declara\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destinar parte do Imposto de Renda a institui\u00e7\u00f5es assistenciais \u00e9 um exerc\u00edcio de cidadania que&#8230;<\/p>\n","protected":false},"author":21,"featured_media":11781723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,19],"tags":[188],"class_list":["post-11781722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-politica","tag-politica"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11781722"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781722\/revisions"}],"predecessor-version":[{"id":11781724,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781722\/revisions\/11781724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11781723"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11781722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11781722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11781722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}