{"id":11781784,"date":"2026-05-13T10:41:00","date_gmt":"2026-05-13T14:41:00","guid":{"rendered":"https:\/\/www.corumbaonline.com.br\/news\/?p=11781784"},"modified":"2026-05-13T11:47:37","modified_gmt":"2026-05-13T15:47:37","slug":"jogos-escolares-de-ms-chapadao-do-sul-sedia-a-primeira-etapa-regional-de-atletismo","status":"publish","type":"post","link":"https:\/\/www.corumbaonline.com.br\/news\/jogos-escolares-de-ms-chapadao-do-sul-sedia-a-primeira-etapa-regional-de-atletismo\/","title":{"rendered":"Jogos Escolares de MS: Chapad\u00e3o do Sul sedia a primeira etapa regional de atletismo"},"content":{"rendered":"<p>Chapad\u00e3o do Sul ser\u00e1 sede, entre os dias 15 e 17 de maio, da primeira etapa regional de atletismo dos Jogos Escolares da Juventude de Mato Grosso do Sul. A competi\u00e7\u00e3o reunir\u00e1 146 atletas de 12 a 14 anos de 12 munic\u00edpios sul-mato-grossenses, nas categorias feminina e masculina. As disputas ser\u00e3o no Complexo Esportivo Municipal, localizado na Avenida Mato Grosso do Sul, s\/n, bairro Flamboyant.<\/p>\n<p>A cerim\u00f4nia oficial de abertura acontecer\u00e1 no dia 15 de maio (sexta-feira), \u00e0s 19 horas, no Conviver (Centro de Conviv\u00eancia do Idoso), situado na Avenida Goi\u00e1s, s\/n, tamb\u00e9m no bairro Flamboyant.<\/p>\n<p>Esta \u00e9 a primeira etapa regional da modalidade de atletismo dos Jogos Escolares da Juventude de Mato Grosso do Sul. Os quatro melhores atletas de cada prova garantir\u00e3o vaga para a segunda etapa da competi\u00e7\u00e3o, que ser\u00e1 realizada em Campo Grande, em data ainda a ser divulgada. O evento \u00e9 realizado pela Fundesporte (Funda\u00e7\u00e3o de Desporto e Lazer) e Setesc (Secretaria de Estado de Turismo, Esporte e Cultura).<\/p>\n<p>Participam desta fase delega\u00e7\u00f5es dos munic\u00edpios de Bataguassu, Cassil\u00e2ndia, Chapad\u00e3o do Sul, Costa Rica, Jaraguari, Nova Andradina, Para\u00edso das \u00c1guas, Parana\u00edba, Pedro Gomes, Ribas do Rio Pardo, Sonora e Tr\u00eas Lagoas.<\/p>\n<p>Durante os tr\u00eas dias de competi\u00e7\u00e3o, os atletas disputar\u00e3o diversas provas do atletismo em busca de bons resultados e da classifica\u00e7\u00e3o para as pr\u00f3ximas fases dos Jogos. A expectativa \u00e9 de grande movimenta\u00e7\u00e3o esportiva no munic\u00edpio, fortalecendo o interc\u00e2mbio entre os participantes e incentivando o desenvolvimento do esporte escolar e de base em Mato Grosso do Sul.<\/p>\n<p>De acordo com o diretor-presidente da Fundesporte, Paulo Ricardo Martins Nu\u00f1ez, o crescimento da modalidade no Estado tornou necess\u00e1ria a divis\u00e3o da competi\u00e7\u00e3o em duas etapas regionais.<\/p>\n<p>\u201c\u00c9 muito importante ver munic\u00edpios de diferentes regi\u00f5es do Estado reunidos em uma competi\u00e7\u00e3o como esta, porque o esporte cria oportunidades, aproxima os jovens e fortalece o trabalho desenvolvido em cada cidade. Chapad\u00e3o do Sul se torna, durante esses dias, um ponto de encontro, recebendo atletas, familiares e comiss\u00e3o t\u00e9cnica, al\u00e9m de movimentar a economia e o com\u00e9rcio local\u201d, destacou.<\/p>\n<p>A diretora dos Jogos Escolares da Juventude de MS, Karina Quaini, ressaltou a import\u00e2ncia de Chapad\u00e3o do Sul sediar a competi\u00e7\u00e3o.<\/p>\n<p>\u201cA divis\u00e3o do atletismo em duas etapas regionais aconteceu devido ao crescimento expressivo no n\u00famero de participantes da modalidade nos Jogos Escolares da Juventude de MS. Por isso organizamos as disputas em duas regionais para garantir uma melhor estrutura de competi\u00e7\u00e3o e possibilitar a classifica\u00e7\u00e3o dos melhores atletas para a etapa estadual. Chapad\u00e3o do Sul foi escolhido para sediar uma das etapas porque o munic\u00edpio conta, atualmente, com uma pista oficial de atletismo totalmente conclu\u00edda, oferecendo uma estrutura adequada para receber uma competi\u00e7\u00e3o desse porte\u201d, finaliza.<\/p>\n<p>Acesse as informa\u00e7\u00f5es completas no\u00a0<a href=\"https:\/\/www.fundesporte.ms.gov.br\/wp-content\/uploads\/2026\/05\/INFORMATIVO-ALTETISMO-REGIONAL-1-CHAPADAO-DO-SUL.pdf\">informativo oficial.<\/a><\/p>\n<p><strong>Jogos Escolares da Juventude de MS &#8211; Etapa 1 Atletismo<\/strong><\/p>\n<p><strong>Cerim\u00f4nia oficial de abertura<\/strong><br \/>\n<strong>Data:<\/strong>\u00a015 de maio (sexta-feira)<br \/>\n<strong>Local:\u00a0<\/strong>Conviver (Centro de Conviv\u00eancia do Idoso)<br \/>\n<strong>Endere\u00e7o:\u00a0<\/strong>Avenida Goi\u00e1s s\/n, bairro Flamboyant<br \/>\n<strong>Hor\u00e1rio:\u00a0<\/strong>19 horas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chapad\u00e3o do Sul ser\u00e1 sede, entre os dias 15 e 17 de maio, da primeira&#8230;<\/p>\n","protected":false},"author":13,"featured_media":11781785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[194],"class_list":["post-11781784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-educacao"],"_links":{"self":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/comments?post=11781784"}],"version-history":[{"count":1,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781784\/revisions"}],"predecessor-version":[{"id":11781786,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/posts\/11781784\/revisions\/11781786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media\/11781785"}],"wp:attachment":[{"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/media?parent=11781784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/categories?post=11781784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corumbaonline.com.br\/news\/wp-json\/wp\/v2\/tags?post=11781784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}